{"id":603,"count":9,"description":"Produtos da Categoria BAROSA Limpeza","link":"https:\/\/www.barosa.com\/fr\/product-category\/limpeza\/","name":"Nettoyage","slug":"limpeza","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":54,"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arquivo de Limpeza - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/fr\/categorie-produit-2\/limpeza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Limpeza\" \/>\n<meta property=\"og:description\" content=\"Produtos da Categoria BAROSA Limpeza\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/fr\/categorie-produit-2\/limpeza\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2024\/02\/BAROSA-Logo-1200-x-675.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/product-category\\\/limpeza\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/product-category\\\/limpeza\\\/\",\"name\":\"Arquivo de Limpeza - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/product-category\\\/limpeza\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/product-category\\\/limpeza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limpeza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arquivo de Limpeza - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/fr\/categorie-produit-2\/limpeza\/","og_locale":"fr_FR","og_type":"article","og_title":"Arquivo de Limpeza","og_description":"Produtos da Categoria BAROSA Limpeza","og_url":"https:\/\/www.barosa.com\/fr\/categorie-produit-2\/limpeza\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2024\/02\/BAROSA-Logo-1200-x-675.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.barosa.com\/product-category\/limpeza\/","url":"https:\/\/www.barosa.com\/product-category\/limpeza\/","name":"Arquivo de Limpeza - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.barosa.com\/product-category\/limpeza\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/product-category\/limpeza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Limpeza"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture\u00ae \". Poissons Crustac\u00e9s Fruits de mer C\u00e9phalopodes Bivalves Boulangerie P\u00e2tisserie Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture !\u00ae \"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat\/603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product?product_cat=603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}