{"id":9411,"date":"2023-05-08T12:29:57","date_gmt":"2023-05-08T11:29:57","guid":{"rendered":"https:\/\/www.barosa.com\/?post_type=product&#038;p=9411"},"modified":"2023-06-05T10:51:02","modified_gmt":"2023-06-05T09:51:02","slug":"dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/fr\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/","title":{"rendered":"Dona Pureza Vinaigre pour le nettoyage des machines (citron) 500ml"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Format:<\/strong><\/p>\n<ul>\n<li>Unit\u00e9 de 500 ml<\/li>\n<\/ul>\n<p><strong>Description :<\/strong> Vinaigre pour le nettoyage des machines avec un parfum de citron.<\/p>\n<pre>ARR\u00caTEZ DE CHANTER ET REPRENEZ LES VIEILLES ASTUCES,\r\nNETTOYER LES MACHINES ET R\u00c9DUIRE LES ODEURS, RIEN DE\r\nRIEN DE MIEUX QUE LE VINAIGRE DE NETTOYAGE.<\/pre>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7280\" src=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/03\/vegan.png\" alt=\"Vegan\" width=\"60\" height=\"55\" srcset=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/03\/vegan.png 110w, https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/03\/vegan-13x12.png 13w\" sizes=\"auto, (max-width: 60px) 100vw, 60px\" \/><\/p>\n<p><strong>Marque:<\/strong> Mme Purity<\/p>","protected":false},"featured_media":9412,"template":"","meta":[],"product_brand":[],"product_cat":[603],"product_tag":[610],"class_list":{"0":"post-9411","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-limpeza","7":"product_tag-dona-pureza","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Deixe-se de cantigas e v\u00e1 pelas dicas antigas, limpeza m\u00e1quinas e redu\u00e7\u00e3o de odores, nada melhor que vinagre de limpar. BAROSA\u00ae FoodService.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/fr\/produit\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml\" \/>\n<meta property=\"og:description\" content=\"Deixe-se de cantigas e v\u00e1 pelas dicas antigas, limpeza m\u00e1quinas e redu\u00e7\u00e3o de odores, nada melhor que vinagre de limpar. BAROSA\u00ae FoodService.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/fr\/produit\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T09:51:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/05\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"695\" \/>\n\t<meta property=\"og:image:height\" content=\"695\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/\",\"name\":\"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg\",\"datePublished\":\"2023-05-08T11:29:57+00:00\",\"dateModified\":\"2023-06-05T09:51:02+00:00\",\"description\":\"Deixe-se de cantigas e v\u00e1 pelas dicas antigas, limpeza m\u00e1quinas e redu\u00e7\u00e3o de odores, nada melhor que vinagre de limpar. BAROSA\u00ae FoodService.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg\",\"width\":695,\"height\":695,\"caption\":\"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dona Pureza Vinaigre de nettoyage pour machine (citron) 500ml - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Arr\u00eatez de chanter et optez pour les bonnes vieilles astuces, nettoyer les machines et r\u00e9duire les odeurs, rien de mieux que le vinaigre pour nettoyer. BAROSA\u00ae FoodService.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/fr\/produit\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/","og_locale":"fr_FR","og_type":"article","og_title":"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml","og_description":"Deixe-se de cantigas e v\u00e1 pelas dicas antigas, limpeza m\u00e1quinas e redu\u00e7\u00e3o de odores, nada melhor que vinagre de limpar. BAROSA\u00ae FoodService.","og_url":"https:\/\/www.barosa.com\/fr\/produit\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2023-06-05T09:51:02+00:00","og_image":[{"width":695,"height":695,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/05\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/","url":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/","name":"Dona Pureza Vinaigre de nettoyage pour machine (citron) 500ml - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/05\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg","datePublished":"2023-05-08T11:29:57+00:00","dateModified":"2023-06-05T09:51:02+00:00","description":"Arr\u00eatez de chanter et optez pour les bonnes vieilles astuces, nettoyer les machines et r\u00e9duire les odeurs, rien de mieux que le vinaigre pour nettoyer. BAROSA\u00ae FoodService.","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/05\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/05\/Dona-Pureza-Vinagre-de-Limpeza-Maquinas-limao-500ml.jpg","width":695,"height":695,"caption":"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/dona-pureza-vinagre-de-limpeza-maquinas-limao-500ml\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Dona Pureza Vinagre de Limpeza Maquinas (lim\u00e3o) 500ml"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture\u00ae \". Poissons Crustac\u00e9s Fruits de mer C\u00e9phalopodes Bivalves Boulangerie P\u00e2tisserie Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture !\u00ae \"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product\/9411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media\/9412"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media?parent=9411"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=9411"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=9411"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=9411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}