{"id":8487,"date":"2022-09-28T15:53:17","date_gmt":"2022-09-28T14:53:17","guid":{"rendered":"https:\/\/www.barosa.com\/?post_type=product&#038;p=8487"},"modified":"2025-04-01T00:00:01","modified_gmt":"2025-04-01T00:00:01","slug":"hellmanns-maionese-2lt","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/fr\/produto\/hellmanns-maionese-2lt\/","title":{"rendered":"Mayonnaise Hellmann's 2Lt"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Formato:<\/strong><\/p>\n<ul>\n<li>Embalagem com 2 Litros<\/li>\n<\/ul>\n<p><strong>Descri\u00e7\u00e3o<\/strong><br \/>\nConfecionada com os melhores ingredientes. Ideal para todo o tipo de aplica\u00e7\u00f5es a quente ou a frio.<\/p>\n<ul>\n<li>100% Genu\u00edna e 100% de Confian\u00e7a<\/li>\n<li>Ideal tanto em receitas frias como quentes<\/li>\n<li>Os ingredientes da sua receita: ovos de galinhas do campo, \u00f3leos 100% vegetais, vinagre e sumo de lim\u00e3o<\/li>\n<li>Sabor e textura inconfund\u00edveis. N\u00e3o humedece o p\u00e3o.<\/li>\n<li>Fonte natural de \u00d3mega 3<\/li>\n<\/ul>\n[bg_collapse view=\"link\" color=\"#4a4949\" expand_text=\"Mostrar mais \u25bc\" collapse_text=\"Mostrar menos \u25b2\" ]<\/p>\n<p><strong>Informa\u00e7\u00e3o diet\u00e9tica<\/strong><br \/>\nOvo Lacto Vegetariano<\/p>\n<p><strong>Alerg\u00e9neos<\/strong><br \/>\nIsento de gl\u00faten<br \/>\nSem lactose<\/p>\n<p><strong>Informa\u00e7\u00e3o diet\u00e9tica<\/strong><br \/>\nOvo Lacto Vegetariano<\/p>\n<p><strong>Prepara\u00e7\u00e3o<\/strong><br \/>\nPronto usar<\/p>\n<p>[\/bg_collapse]\n<p><strong>Marca:<\/strong> Hellmann\u2019s<\/p>\n","protected":false},"featured_media":8488,"template":"","meta":[],"product_brand":[],"product_cat":[232],"product_tag":[],"class_list":{"0":"post-8487","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-molhos-frios","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hellmann&#039;s Maionese 2Lt - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Confecionada com os melhores ingredientes. Ideal para todo o tipo de aplica\u00e7\u00f5es a quente ou a frio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/fr\/produit\/hellmanns-maionese-2lt\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hellmann&#039;s Maionese 2Lt\" \/>\n<meta property=\"og:description\" content=\"Confecionada com os melhores ingredientes. Ideal para todo o tipo de aplica\u00e7\u00f5es a quente ou a frio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/fr\/produit\/hellmanns-maionese-2lt\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-01T00:00:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/09\/Hellmann-s-Maionese-2Lt.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/\",\"name\":\"Hellmann's Maionese 2Lt - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Hellmann-s-Maionese-2Lt.jpg\",\"datePublished\":\"2022-09-28T14:53:17+00:00\",\"dateModified\":\"2025-04-01T00:00:01+00:00\",\"description\":\"Confecionada com os melhores ingredientes. Ideal para todo o tipo de aplica\u00e7\u00f5es a quente ou a frio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Hellmann-s-Maionese-2Lt.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Hellmann-s-Maionese-2Lt.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Hellmann's Maionese 2Lt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/hellmanns-maionese-2lt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hellmann&#8217;s Maionese 2Lt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hellmann's Mayonnaise 2Lt - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Fabriqu\u00e9 avec les meilleurs ingr\u00e9dients. Id\u00e9al pour tous les types d'applications chaudes ou froides.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/fr\/produit\/hellmanns-maionese-2lt\/","og_locale":"fr_FR","og_type":"article","og_title":"Hellmann's Maionese 2Lt","og_description":"Confecionada com os melhores ingredientes. Ideal para todo o tipo de aplica\u00e7\u00f5es a quente ou a frio.","og_url":"https:\/\/www.barosa.com\/fr\/produit\/hellmanns-maionese-2lt\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2025-04-01T00:00:01+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/09\/Hellmann-s-Maionese-2Lt.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/","url":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/","name":"Hellmann's Mayonnaise 2Lt - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/09\/Hellmann-s-Maionese-2Lt.jpg","datePublished":"2022-09-28T14:53:17+00:00","dateModified":"2025-04-01T00:00:01+00:00","description":"Fabriqu\u00e9 avec les meilleurs ingr\u00e9dients. Id\u00e9al pour tous les types d'applications chaudes ou froides.","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/09\/Hellmann-s-Maionese-2Lt.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/09\/Hellmann-s-Maionese-2Lt.jpg","width":1000,"height":1000,"caption":"Hellmann's Maionese 2Lt"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/hellmanns-maionese-2lt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Hellmann&#8217;s Maionese 2Lt"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture\u00ae \". Poissons Crustac\u00e9s Fruits de mer C\u00e9phalopodes Bivalves Boulangerie P\u00e2tisserie Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture !\u00ae \"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media\/8488"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=8487"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=8487"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}