{"id":3785,"date":"2019-11-19T12:06:23","date_gmt":"2019-11-19T12:06:23","guid":{"rendered":"http:\/\/www.barosa.com\/?post_type=product&#038;p=3785"},"modified":"2023-08-16T16:56:12","modified_gmt":"2023-08-16T15:56:12","slug":"pimentos-mix-fatias","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/fr\/produto\/pimentos-mix-fatias\/","title":{"rendered":"Poivrons m\u00e9lang\u00e9s en tranches"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Type d'emballage:<\/p>\n<ul>\n<li>Emball\u00e9 dans des sacs de 2,5 kg<\/li>\n<li>Nombre de sacs : 4<\/li>\n<li>Poids par carton: 10 Kg<\/li>\n<\/ul>\n<p>Marque: Ardo<\/p>\n<h6><em>Produit surgel\u00e9<\/em><\/h6>","protected":false},"featured_media":10000,"template":"","meta":[],"product_brand":[],"product_cat":[182],"product_tag":[],"class_list":{"0":"post-3785","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-vegetais-catering","7":"pa_preco-210e","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pimentos Mix Fatias - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/fr\/produit\/pimentos-mix-fatias\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pimentos Mix Fatias\" \/>\n<meta property=\"og:description\" content=\"Tipo de embalagem:   Embalado em sacos de 2,5 Kg  Numero de sacos: 4  Peso por caixa: 10 Kg  Marca: Ardo Produto congelado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/fr\/produit\/pimentos-mix-fatias\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T15:56:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/08\/Pimento-Tiras-Verde-e-Vermelho.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/\",\"name\":\"Pimentos Mix Fatias - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pimento-Tiras-Verde-e-Vermelho.jpg\",\"datePublished\":\"2019-11-19T12:06:23+00:00\",\"dateModified\":\"2023-08-16T15:56:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pimento-Tiras-Verde-e-Vermelho.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pimento-Tiras-Verde-e-Vermelho.jpg\",\"width\":1000,\"height\":1000,\"caption\":\"Pimento Tiras Verde e Vermelho\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pimentos-mix-fatias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pimentos Mix Fatias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"M\u00e9lange de piments en tranches - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/fr\/produit\/pimentos-mix-fatias\/","og_locale":"fr_FR","og_type":"article","og_title":"Pimentos Mix Fatias","og_description":"Tipo de embalagem:   Embalado em sacos de 2,5 Kg  Numero de sacos: 4  Peso por caixa: 10 Kg  Marca: Ardo Produto congelado","og_url":"https:\/\/www.barosa.com\/fr\/produit\/pimentos-mix-fatias\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2023-08-16T15:56:12+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/08\/Pimento-Tiras-Verde-e-Vermelho.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/","url":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/","name":"M\u00e9lange de piments en tranches - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/08\/Pimento-Tiras-Verde-e-Vermelho.jpg","datePublished":"2019-11-19T12:06:23+00:00","dateModified":"2023-08-16T15:56:12+00:00","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/08\/Pimento-Tiras-Verde-e-Vermelho.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2023\/08\/Pimento-Tiras-Verde-e-Vermelho.jpg","width":1000,"height":1000,"caption":"Pimento Tiras Verde e Vermelho"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/pimentos-mix-fatias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Pimentos Mix Fatias"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture\u00ae \". Poissons Crustac\u00e9s Fruits de mer C\u00e9phalopodes Bivalves Boulangerie P\u00e2tisserie Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture !\u00ae \"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product\/3785","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media\/10000"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media?parent=3785"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3785"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3785"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3785"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}