{"id":3273,"date":"2019-11-13T13:00:25","date_gmt":"2019-11-13T13:00:25","guid":{"rendered":"http:\/\/www.barosa.com\/?post_type=product&#038;p=3273"},"modified":"2021-08-04T09:07:58","modified_gmt":"2021-08-04T09:07:58","slug":"peixe-vermelho-m-01","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/fr\/produto\/peixe-vermelho-m-01\/","title":{"rendered":"Poisson rouge M"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong><em>Sebastes Mentella<\/em><\/strong><br \/>\nAtlantique nord-ouest captur\u00e9<\/p>\n<p>Type d'emballage:<\/p>\n<ul>\n<li>Emball\u00e9 dans des sachets en plastique<\/li>\n<li>Nombre de sachets: 10<\/li>\n<li>Poids unitaire: 700 g (poids net \u00e9goutt\u00e9)<\/li>\n<\/ul>\n<p><strong>Marque:<\/strong> Barosa<\/p>\n<h6><em>Produit surgel\u00e9<\/em><\/h6>","protected":false},"featured_media":4526,"template":"","meta":[],"product_brand":[],"product_cat":[601],"product_tag":[],"class_list":{"0":"post-3273","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pescados-embalados","7":"pa_preco-495e","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Peixe Vermelho M - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Embalado em saquetas, Sebastes Mentella, Cap Atl. Noroeste, &quot;BAROSA N\u00e3o h\u00e1 bom garfo que resista&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/fr\/produit\/peixe-vermelho-m-01\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peixe Vermelho M\" \/>\n<meta property=\"og:description\" content=\"Embalado em saquetas, Sebastes Mentella, Cap Atl. Noroeste, &quot;BAROSA N\u00e3o h\u00e1 bom garfo que resista&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/fr\/produit\/peixe-vermelho-m-01\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-04T09:07:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/\",\"name\":\"Peixe Vermelho M - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25001.jpg\",\"datePublished\":\"2019-11-13T13:00:25+00:00\",\"dateModified\":\"2021-08-04T09:07:58+00:00\",\"description\":\"Embalado em saquetas, Sebastes Mentella, Cap Atl. Noroeste, \\\"BAROSA N\u00e3o h\u00e1 bom garfo que resista\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25001.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Peixe Vermelho M\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/peixe-vermelho-m-01\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Peixe Vermelho M\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Poisson rouge M - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Conditionn\u00e9 en sachets, Sebastes Mentella, Cap Atl. Noroeste, \"BAROSA No good fork can resist\".\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/fr\/produit\/peixe-vermelho-m-01\/","og_locale":"fr_FR","og_type":"article","og_title":"Peixe Vermelho M","og_description":"Embalado em saquetas, Sebastes Mentella, Cap Atl. Noroeste, \"BAROSA N\u00e3o h\u00e1 bom garfo que resista\"","og_url":"https:\/\/www.barosa.com\/fr\/produit\/peixe-vermelho-m-01\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2021-08-04T09:07:58+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/","url":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/","name":"Poisson rouge M - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25001.jpg","datePublished":"2019-11-13T13:00:25+00:00","dateModified":"2021-08-04T09:07:58+00:00","description":"Conditionn\u00e9 en sachets, Sebastes Mentella, Cap Atl. Noroeste, \"BAROSA No good fork can resist\".\"","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25001.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25001.jpg","width":1280,"height":1280,"caption":"Peixe Vermelho M"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/peixe-vermelho-m-01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Peixe Vermelho M"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture\u00ae \". Poissons Crustac\u00e9s Fruits de mer C\u00e9phalopodes Bivalves Boulangerie P\u00e2tisserie Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Entreprise de transformation et commercialisation de produits alimentaires surgel\u00e9s. BAROSA \u00ae Pescados, \" Aucune bonne fourchette ne peut y r\u00e9sister\u00ae \". BAROSA \u00ae FoodService \" Le bon c\u00f4t\u00e9 de la nourriture !\u00ae \"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media\/4526"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/media?parent=3273"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_brand?post=3273"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_cat?post=3273"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/fr\/wp-json\/wp\/v2\/product_tag?post=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}