{"id":5375,"date":"2020-04-07T19:53:00","date_gmt":"2020-04-07T19:53:00","guid":{"rendered":"http:\/\/www.barosa.com\/?post_type=product&#038;p=5375"},"modified":"2022-09-19T22:42:27","modified_gmt":"2022-09-19T21:42:27","slug":"manteiga-com-sal-10grs-mimosa","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/en\/produto\/manteiga-com-sal-10grs-mimosa\/","title":{"rendered":"Salted butter 8 grams (Mimosa)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Format:<\/strong><\/p>\n<ul>\n<li>Net weight: 8 Grs<\/li>\n<li>Box: 100 units<\/li>\n<\/ul>\n<p><strong>Product description<\/strong><\/p>\n<p>Mimosa butter with salt is traditional butter with all its unique and original flavour. Butter is a natural product, without any artificial processing or additives. Always with us, at various times of the day, butter goes naturally with meals and adds that magical touch to your breakfast and snack.<\/p>\n<p><strong>Brand:<\/strong> Mimosa<\/p>","protected":false},"featured_media":8426,"template":"","meta":[],"product_brand":[],"product_cat":[356],"product_tag":[],"class_list":{"0":"post-5375","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cremes-vegetais-manteigas","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Manteiga com sal 8 grs (Mimosa) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Manteiga Mimosa com sal \u00e9 a manteiga tradicional, com todo o seu sabor \u00fanico e original. A manteiga \u00e9 um produto natural, sem qualquer processo de transforma\u00e7\u00e3o artificial e sem aditivos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/en\/product-2\/manteiga-com-sal-10grs-mimosa\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Manteiga com sal 8 grs (Mimosa)\" \/>\n<meta property=\"og:description\" content=\"Manteiga Mimosa com sal \u00e9 a manteiga tradicional, com todo o seu sabor \u00fanico e original. A manteiga \u00e9 um produto natural, sem qualquer processo de transforma\u00e7\u00e3o artificial e sem aditivos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/en\/product-2\/manteiga-com-sal-10grs-mimosa\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-19T21:42:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2020\/04\/Manteiga-Mimosa-Tradicional-8-Grs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"493\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/\",\"name\":\"Manteiga com sal 8 grs (Mimosa) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Manteiga-Mimosa-Tradicional-8-Grs.jpg\",\"datePublished\":\"2020-04-07T19:53:00+00:00\",\"dateModified\":\"2022-09-19T21:42:27+00:00\",\"description\":\"Manteiga Mimosa com sal \u00e9 a manteiga tradicional, com todo o seu sabor \u00fanico e original. A manteiga \u00e9 um produto natural, sem qualquer processo de transforma\u00e7\u00e3o artificial e sem aditivos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Manteiga-Mimosa-Tradicional-8-Grs.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/Manteiga-Mimosa-Tradicional-8-Grs.jpg\",\"width\":493,\"height\":493,\"caption\":\"Manteiga Mimosa Tradicional 8 Grs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/manteiga-com-sal-10grs-mimosa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Manteiga com sal 8 grs (Mimosa)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Salted butter 8 grs (Mimosa) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Mimosa butter with salt is traditional butter with all its unique and original flavour. The butter is a natural product, without any artificial processing or additives.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/en\/product-2\/manteiga-com-sal-10grs-mimosa\/","og_locale":"en_GB","og_type":"article","og_title":"Manteiga com sal 8 grs (Mimosa)","og_description":"Manteiga Mimosa com sal \u00e9 a manteiga tradicional, com todo o seu sabor \u00fanico e original. A manteiga \u00e9 um produto natural, sem qualquer processo de transforma\u00e7\u00e3o artificial e sem aditivos.","og_url":"https:\/\/www.barosa.com\/en\/product-2\/manteiga-com-sal-10grs-mimosa\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2022-09-19T21:42:27+00:00","og_image":[{"width":493,"height":493,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2020\/04\/Manteiga-Mimosa-Tradicional-8-Grs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/","url":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/","name":"Salted butter 8 grs (Mimosa) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2020\/04\/Manteiga-Mimosa-Tradicional-8-Grs.jpg","datePublished":"2020-04-07T19:53:00+00:00","dateModified":"2022-09-19T21:42:27+00:00","description":"Mimosa butter with salt is traditional butter with all its unique and original flavour. The butter is a natural product, without any artificial processing or additives.","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2020\/04\/Manteiga-Mimosa-Tradicional-8-Grs.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2020\/04\/Manteiga-Mimosa-Tradicional-8-Grs.jpg","width":493,"height":493,"caption":"Manteiga Mimosa Tradicional 8 Grs"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/manteiga-com-sal-10grs-mimosa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Manteiga com sal 8 grs (Mimosa)"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Frozen Foods | Manuel de Sousa Barosa, Ltd.","description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Seafood, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food\u00ae\". Seafood Crustaceans Shellfish Cephalopods Bivalves Bakery Pastries Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Ltd.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Pescados, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food!\u00ae\"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product\/5375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media\/8426"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media?parent=5375"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_brand?post=5375"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_cat?post=5375"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_tag?post=5375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}