{"id":4362,"date":"2019-11-26T23:49:18","date_gmt":"2019-11-26T22:49:18","guid":{"rendered":"http:\/\/www.barosa.com\/?post_type=product&#038;p=4362"},"modified":"2023-08-24T18:40:42","modified_gmt":"2023-08-24T17:40:42","slug":"knorr-primerba-tempero-pasta-manjericao-340gr","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/en\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/","title":{"rendered":"Knorr Primerba seasoning paste Basil 340Gr"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Formato: <\/strong>Embalagem com 340 grs<\/p>\n<p><strong>Descri\u00e7\u00e3o<\/strong><br \/>\nErvas frescas conservadas em \u00f3leo vegetal. Cont\u00e9m o equivalente a 3 Kg de manjeric\u00e3o fresco. Isento de gl\u00faten.<\/p>\n[bg_collapse view=\"link\" color=\"#4a4949\" icon=\"arrow\" expand_text=\"\u00a0 \u00a0Mostrar mais\" collapse_text=\"\u00a0 \u00a0Mostrar menos\" ]<\/p>\n<p><strong>Prepara\u00e7\u00e3o<\/strong><br \/>\nKNORR Primerba oferece o sabor e os aromas distintos de ervas frescas durante todo o ano. Utilize para dar sabor \u00e0s suas receitas independentemente da \u00e9poca. Utilizando um processo \u00fanico de fabrico conjuga-se o sabor distinto de ervas frescas com \u00f3leo vegetal. De f\u00e1cil utiliza\u00e7\u00e3o &#8211; a quente e a frio- sendo altamente concentrado, utilize com modera\u00e7\u00e3o de forma a intensificar o sabor das suas confec\u00e7\u00f5es. Knorr Primerba \u00e9 o complemento ideal para sopas, molhos, saladas, sal, massas, carnes e bases de tomate. Pode igualmente juntar maionese ou natas para criar um apetitoso molho.<\/p>\n<p><strong>Aditivos<\/strong><br \/>\nSem corantes artif\u00edciais<br \/>\nSem aromas artif\u00edciais<\/p>\n<p><strong>Alerg\u00e9neos<\/strong><br \/>\nIsento de gl\u00faten<\/p>\n<p><strong>Marca:<\/strong> Knorr<\/p>\n<p>[\/bg_collapse]\n","protected":false},"featured_media":4363,"template":"","meta":[],"product_brand":[],"product_cat":[364],"product_tag":[],"class_list":{"0":"post-4362","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-temperos-graos","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/en\/product-2\/knorr-primerba-tempero-pasta-manjericao-340gr\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr\" \/>\n<meta property=\"og:description\" content=\"Formato: Embalagem com 340 grs  Descri\u00e7\u00e3o Ervas frescas conservadas em \u00f3leo vegetal. Cont\u00e9m o equivalente a 3 Kg de manjeric\u00e3o fresco. Isento de gl\u00faten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/en\/product-2\/knorr-primerba-tempero-pasta-manjericao-340gr\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-24T17:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25010101.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/\",\"name\":\"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25010101.jpg\",\"datePublished\":\"2019-11-26T22:49:18+00:00\",\"dateModified\":\"2023-08-24T17:40:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25010101.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/25010101.jpg\",\"width\":450,\"height\":450,\"caption\":\"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/knorr-primerba-tempero-pasta-manjericao-340gr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Knorr Primerba seasoning paste Basil 340Gr - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/en\/product-2\/knorr-primerba-tempero-pasta-manjericao-340gr\/","og_locale":"en_GB","og_type":"article","og_title":"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr","og_description":"Formato: Embalagem com 340 grs  Descri\u00e7\u00e3o Ervas frescas conservadas em \u00f3leo vegetal. Cont\u00e9m o equivalente a 3 Kg de manjeric\u00e3o fresco. Isento de gl\u00faten.","og_url":"https:\/\/www.barosa.com\/en\/product-2\/knorr-primerba-tempero-pasta-manjericao-340gr\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2023-08-24T17:40:42+00:00","og_image":[{"width":450,"height":450,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25010101.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/","url":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/","name":"Knorr Primerba seasoning paste Basil 340Gr - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25010101.jpg","datePublished":"2019-11-26T22:49:18+00:00","dateModified":"2023-08-24T17:40:42+00:00","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25010101.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/25010101.jpg","width":450,"height":450,"caption":"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/knorr-primerba-tempero-pasta-manjericao-340gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Knorr Primerba tempero pasta Manjeric\u00e3o 340Gr"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Frozen Foods | Manuel de Sousa Barosa, Ltd.","description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Seafood, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food\u00ae\". Seafood Crustaceans Shellfish Cephalopods Bivalves Bakery Pastries Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Ltd.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Pescados, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food!\u00ae\"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product\/4362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media\/4363"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media?parent=4362"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_brand?post=4362"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_cat?post=4362"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_tag?post=4362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}