{"id":3317,"date":"2019-11-13T19:29:33","date_gmt":"2019-11-13T19:29:33","guid":{"rendered":"http:\/\/www.barosa.com\/?post_type=product&#038;p=3317"},"modified":"2020-01-08T23:19:51","modified_gmt":"2020-01-08T23:19:51","slug":"pescada-3-04","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/en\/produto\/pescada-3-04\/","title":{"rendered":"Hake 3"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong><em>Merluccius capensis\/paradoxus<\/em><\/strong><br \/>\nCapt. Southeast Atlantic<\/p>\n<p>Packaging type:<\/p>\n<ul>\n<li>Hygienized individual packaging, piece by piece<\/li>\n<li>Box weight: 6 Kg (net weight)<\/li>\n<\/ul>\n<p><strong>Brand:<\/strong> Barosa<\/p>\n<h6><em>Frozen product<\/em><\/h6>","protected":false},"featured_media":5117,"template":"","meta":[],"product_brand":[],"product_cat":[72],"product_tag":[],"class_list":{"0":"post-3317","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pescados-higienizados","7":"pa_preco-590e","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pescada 3 - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Pescada 3 em embalagem individual higienizada posta a posta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/en\/product-2\/pescada-3-04\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pescada 3\" \/>\n<meta property=\"og:description\" content=\"Pescada 3 em embalagem individual higienizada posta a posta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/en\/product-2\/pescada-3-04\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-01-08T23:19:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-32004-new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/\",\"name\":\"Pescada 3 - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-32004-new.jpg\",\"datePublished\":\"2019-11-13T19:29:33+00:00\",\"dateModified\":\"2020-01-08T23:19:51+00:00\",\"description\":\"Pescada 3 em embalagem individual higienizada posta a posta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-32004-new.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-32004-new.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Pescada 3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/pescada-3-04\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pescada 3\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hake 3 - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Hake 3 in individual, sanitised packages.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/en\/product-2\/pescada-3-04\/","og_locale":"en_GB","og_type":"article","og_title":"Pescada 3","og_description":"Pescada 3 em embalagem individual higienizada posta a posta.","og_url":"https:\/\/www.barosa.com\/en\/product-2\/pescada-3-04\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2020-01-08T23:19:51+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-32004-new.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/","url":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/","name":"Hake 3 - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-32004-new.jpg","datePublished":"2019-11-13T19:29:33+00:00","dateModified":"2020-01-08T23:19:51+00:00","description":"Hake 3 in individual, sanitised packages.","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/pescada-3-04\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-32004-new.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-32004-new.jpg","width":1280,"height":1280,"caption":"Pescada 3"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/pescada-3-04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Pescada 3"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Frozen Foods | Manuel de Sousa Barosa, Ltd.","description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Seafood, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food\u00ae\". Seafood Crustaceans Shellfish Cephalopods Bivalves Bakery Pastries Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Ltd.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Company specialising in the processing and marketing of frozen food products. BAROSA \u00ae Pescados, \"No good fork can resist\u00ae\". BAROSA \u00ae FoodService \"The good side of food!\u00ae\"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product\/3317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media\/5117"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/media?parent=3317"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_brand?post=3317"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_cat?post=3317"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/en\/wp-json\/wp\/v2\/product_tag?post=3317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}