{"id":7388,"date":"2022-04-06T18:54:38","date_gmt":"2022-04-06T17:54:38","guid":{"rendered":"https:\/\/www.barosa.com\/?post_type=product&#038;p=7388"},"modified":"2022-04-06T18:57:49","modified_gmt":"2022-04-06T17:57:49","slug":"fantasia-de-papel-animais-sortidos-pequenos","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/de\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/","title":{"rendered":"Papierkost\u00fcm - Kleine sortierte Tiere"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Schachtel mit 200<\/p>\n<p><strong>Marke:<\/strong> Progelcone<\/p>","protected":false},"featured_media":7389,"template":"","meta":[],"product_brand":[],"product_cat":[539],"product_tag":[],"class_list":{"0":"post-7388","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-servico-de-apoio","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fantasia de Papel - Animais Sortidos Pequenos - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"description\" content=\"Caixa com 200 unidades\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/de\/product-2\/fantasia-de-papel-animais-sortidos-pequenos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fantasia de Papel - Animais Sortidos Pequenos\" \/>\n<meta property=\"og:description\" content=\"Caixa com 200 unidades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/de\/product-2\/fantasia-de-papel-animais-sortidos-pequenos\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-06T17:57:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/04\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"925\" \/>\n\t<meta property=\"og:image:height\" content=\"925\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/\",\"name\":\"Fantasia de Papel - Animais Sortidos Pequenos - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg\",\"datePublished\":\"2022-04-06T17:54:38+00:00\",\"dateModified\":\"2022-04-06T17:57:49+00:00\",\"description\":\"Caixa com 200 unidades\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg\",\"width\":925,\"height\":925,\"caption\":\"Fantasia de Papel - Animais Sortidos Pequenos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/fantasia-de-papel-animais-sortidos-pequenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fantasia de Papel &#8211; Animais Sortidos Pequenos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fantasia de Papel - Animais Sortidos Pequenos - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Schachtel mit 200","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/de\/product-2\/fantasia-de-papel-animais-sortidos-pequenos\/","og_locale":"de_DE","og_type":"article","og_title":"Fantasia de Papel - Animais Sortidos Pequenos","og_description":"Caixa com 200 unidades","og_url":"https:\/\/www.barosa.com\/de\/product-2\/fantasia-de-papel-animais-sortidos-pequenos\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2022-04-06T17:57:49+00:00","og_image":[{"width":925,"height":925,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/04\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/","url":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/","name":"Fantasia de Papel - Animais Sortidos Pequenos - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/04\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg","datePublished":"2022-04-06T17:54:38+00:00","dateModified":"2022-04-06T17:57:49+00:00","description":"Schachtel mit 200","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/04\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2022\/04\/Animais-Sortidos-Pequenos-Fantasia-de-Papel.jpg","width":925,"height":925,"caption":"Fantasia de Papel - Animais Sortidos Pequenos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/fantasia-de-papel-animais-sortidos-pequenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Fantasia de Papel &#8211; Animais Sortidos Pequenos"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Ein Unternehmen, das Tiefk\u00fchlkostprodukte verarbeitet und verkauft. BAROSA \u00ae Fisch, \"Keine gute Gabel kann widerstehen\u00ae\". BAROSA \u00ae FoodService \"Die gute Seite des Essens\u00ae\". Fisch Krustentiere Schalentiere Kopff\u00fc\u00dfer Muscheln B\u00e4ckerei Geb\u00e4ck Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Ein Unternehmen, das Tiefk\u00fchlkostprodukte verarbeitet und verkauft. BAROSA \u00ae Fisch, \"Keine gute Gabel kann widerstehen\u00ae\". BAROSA \u00ae FoodService \"Die gute Seite des Essens!\u00ae\"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product\/7388","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/media\/7389"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/media?parent=7388"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_brand?post=7388"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_cat?post=7388"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_tag?post=7388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}