{"id":19369,"date":"2025-11-18T22:59:31","date_gmt":"2025-11-18T21:59:31","guid":{"rendered":"https:\/\/www.barosa.com\/?post_type=product&#038;p=19369"},"modified":"2025-11-18T23:02:09","modified_gmt":"2025-11-18T22:02:09","slug":"favas-jardim-verde","status":"publish","type":"product","link":"https:\/\/www.barosa.com\/de\/produto\/favas-jardim-verde\/","title":{"rendered":"Puffbohnen (Green Garden)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Verpackungsart:<\/p>\n<ul>\n<li>Verpackt in 2,5kg S\u00e4cken<\/li>\n<li>Anzahl der Taschen: 4<\/li>\n<li>Gewicht pro Box: 10kg<\/li>\n<\/ul>\n<h6><em>Tiefk\u00fchlprodukt<\/em><\/h6>","protected":false},"featured_media":4808,"template":"","meta":[],"product_brand":[766],"product_cat":[182],"product_tag":[],"class_list":{"0":"post-19369","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-jardim-verde","7":"product_cat-vegetais-catering","8":"pa_preco-240e","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Favas (Jardim Verde) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.barosa.com\/de\/product-2\/favas-jardim-verde\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Favas (Jardim Verde)\" \/>\n<meta property=\"og:description\" content=\"Tipo de embalagem:   Embalado em sacos de 2,5 Kg  Numero de sacos: 4  Peso por caixa: 10 Kg  Produto congelado\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.barosa.com\/de\/product-2\/favas-jardim-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/barosa\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-18T22:02:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-726.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@barosa_lda\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/\",\"name\":\"Favas (Jardim Verde) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-726.jpg\",\"datePublished\":\"2025-11-18T21:59:31+00:00\",\"dateModified\":\"2025-11-18T22:02:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-726.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/F3-726.jpg\",\"width\":1280,\"height\":1280,\"caption\":\"Favas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/produto\\\/favas-jardim-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.barosa.com\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Favas (Jardim Verde)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#website\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"name\":\"BAROSA Congelados | Manuel de Sousa Barosa, Lda.\",\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, &quot;N\u00e3o h\u00e1 bom garfo que resista\u00ae&quot;. BAROSA \u00ae FoodService &quot;O lado bom da comida\u00ae&quot;. Pescados Crust\u00e1ceos Mariscos Cefal\u00f3podes Bivalves Padaria Pastelaria Pizzas Sobremesas\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\"},\"alternateName\":\"BAROSA\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.barosa.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#organization\",\"name\":\"Manuel de Sousa Barosa, Lda.\",\"alternateName\":\"BAROSA\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.barosa.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/BAROSA-Logo-696x696-1.jpg\",\"width\":696,\"height\":696,\"caption\":\"Manuel de Sousa Barosa, Lda.\"},\"image\":{\"@id\":\"https:\\\/\\\/www.barosa.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"http:\\\/\\\/www.facebook.com\\\/barosa\\\/\",\"https:\\\/\\\/x.com\\\/barosa_lda\",\"https:\\\/\\\/www.instagram.com\\\/barosa_lda\\\/\",\"https:\\\/\\\/pt.linkedin.com\\\/company\\\/barosa-lda\"],\"description\":\"Empresa de transforma\u00e7\u00e3o e comercializa\u00e7\u00e3o de produtos alimentares congelados. BAROSA \u00ae Pescados, \\\"N\u00e3o h\u00e1 bom garfo que resista\u00ae\\\". BAROSA \u00ae FoodService \\\"O lado bom da comida!\u00ae\\\"\",\"email\":\"info@barosa.com\",\"telephone\":\"+351 262824403\",\"legalName\":\"Manuel de Sousa Barosa, Lda.\",\"foundingDate\":\"1975-05-21\",\"vatID\":\"503365190\",\"taxID\":\"503365190\",\"duns\":\"452388713\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"ethicsPolicy\":\"https:\\\/\\\/www.barosa.com\\\/politicaprivacidade\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dicke Bohnen (Gr\u00fcner Garten) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.barosa.com\/de\/product-2\/favas-jardim-verde\/","og_locale":"de_DE","og_type":"article","og_title":"Favas (Jardim Verde)","og_description":"Tipo de embalagem:   Embalado em sacos de 2,5 Kg  Numero de sacos: 4  Peso por caixa: 10 Kg  Produto congelado","og_url":"https:\/\/www.barosa.com\/de\/product-2\/favas-jardim-verde\/","og_site_name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","article_publisher":"http:\/\/www.facebook.com\/barosa\/","article_modified_time":"2025-11-18T22:02:09+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-726.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@barosa_lda","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/","url":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/","name":"Dicke Bohnen (Gr\u00fcner Garten) - BAROSA Congelados | Manuel de Sousa Barosa, Lda.","isPartOf":{"@id":"https:\/\/www.barosa.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/#primaryimage"},"image":{"@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-726.jpg","datePublished":"2025-11-18T21:59:31+00:00","dateModified":"2025-11-18T22:02:09+00:00","breadcrumb":{"@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/#primaryimage","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-726.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2019\/11\/F3-726.jpg","width":1280,"height":1280,"caption":"Favas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.barosa.com\/produto\/favas-jardim-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.barosa.com\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.barosa.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Favas (Jardim Verde)"}]},{"@type":"WebSite","@id":"https:\/\/www.barosa.com\/#website","url":"https:\/\/www.barosa.com\/","name":"BAROSA Congelados | Manuel de Sousa Barosa, Lda.","description":"Ein Unternehmen, das Tiefk\u00fchlkostprodukte verarbeitet und verkauft. BAROSA \u00ae Fisch, \"Keine gute Gabel kann widerstehen\u00ae\". BAROSA \u00ae FoodService \"Die gute Seite des Essens\u00ae\". Fisch Krustentiere Schalentiere Kopff\u00fc\u00dfer Muscheln B\u00e4ckerei Geb\u00e4ck Pizzas Desserts","publisher":{"@id":"https:\/\/www.barosa.com\/#organization"},"alternateName":"BAROSA\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.barosa.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.barosa.com\/#organization","name":"Manuel de Sousa Barosa, Lda.","alternateName":"BAROSA","url":"https:\/\/www.barosa.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","contentUrl":"https:\/\/www.barosa.com\/wp-content\/uploads\/2025\/03\/BAROSA-Logo-696x696-1.jpg","width":696,"height":696,"caption":"Manuel de Sousa Barosa, Lda."},"image":{"@id":"https:\/\/www.barosa.com\/#\/schema\/logo\/image\/"},"sameAs":["http:\/\/www.facebook.com\/barosa\/","https:\/\/x.com\/barosa_lda","https:\/\/www.instagram.com\/barosa_lda\/","https:\/\/pt.linkedin.com\/company\/barosa-lda"],"description":"Ein Unternehmen, das Tiefk\u00fchlkostprodukte verarbeitet und verkauft. BAROSA \u00ae Fisch, \"Keine gute Gabel kann widerstehen\u00ae\". BAROSA \u00ae FoodService \"Die gute Seite des Essens!\u00ae\"","email":"info@barosa.com","telephone":"+351 262824403","legalName":"Manuel de Sousa Barosa, Lda.","foundingDate":"1975-05-21","vatID":"503365190","taxID":"503365190","duns":"452388713","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"ethicsPolicy":"https:\/\/www.barosa.com\/politicaprivacidade\/"}]}},"_links":{"self":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product\/19369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/media\/4808"}],"wp:attachment":[{"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/media?parent=19369"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_brand?post=19369"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_cat?post=19369"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.barosa.com\/de\/wp-json\/wp\/v2\/product_tag?post=19369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}